{"id":4697,"date":"2023-10-18T11:42:02","date_gmt":"2023-10-18T14:42:02","guid":{"rendered":"https:\/\/diabahia.com.br\/?p=4697"},"modified":"2023-10-18T11:42:04","modified_gmt":"2023-10-18T14:42:04","slug":"arthur-maia-se-irrita-apos-zambelli-ler-xingamentos-durante-sessao-na-cpmi-do-8-de-janeiro","status":"publish","type":"post","link":"https:\/\/diabahia.com.br\/index.php\/2023\/10\/18\/arthur-maia-se-irrita-apos-zambelli-ler-xingamentos-durante-sessao-na-cpmi-do-8-de-janeiro\/","title":{"rendered":"Arthur Maia se irrita ap\u00f3s Zambelli ler xingamentos durante sess\u00e3o na CPMI do 8 de janeiro"},"content":{"rendered":"\n<p>Durante sess\u00e3o da Comiss\u00e3o Parlamentar Mista de Inqu\u00e9rito (CPMI) do 8 de janeiro desta quarta-feira (18), a deputada federal Carla Zambelli (PL-SP) citou xingamentos que recebeu em suas redes sociais, o que irritou o presidente do colegiado, o baiano Arthur Maia (Uni\u00e3o).<\/p>\n\n\n\n<p>No relat\u00f3rio da senadora Eliziane Gama (PSD-MA)\u00a0que inclui nomes,\u00a0como o do ex-presidente Jair Bolsonaro (PL), e pede o indiciamento de 61 pessoas, Zambelli foi a \u00fanica parlamentar citada. Arthur Maia concedeu, ent\u00e3o, tr\u00eas minutos para a colega se explicar\u00a0ap\u00f3s a cita\u00e7\u00e3o. Ao dar in\u00edcio \u00e0 sua fala, Carla Zambelli\u00a0citou coment\u00e1rios em redes sociais, e logo o presidente da CPMI a interrompeu e solicitou que as palavras da parlamentar fossem retiradas da ata.<\/p>\n\n\n\n<p>\u201cEu estou lhe concedendo a palavra com todo o respeito, mas isso aqui n\u00e3o \u00e9 lugar de se falar pornografia. Respeite esse ambiente. N\u00f3s como pessoas p\u00fablicas somos ofendidos nas redes sociais, mas isso n\u00e3o d\u00e1 o direito de virmos em uma CPMI transmitida para o pa\u00eds inteiro e proferir palavras de baixo cal\u00e3o\u201d, afirmou.<\/p>\n\n\n\n<p>A parlamentar se tornou um dos alvos da CPMI ap\u00f3s o\u00a0hacker Walter Delgatti Netto afirmar que teria participado de reuni\u00e3o\u00a0com Zambelli e com o ex-presidente Jair Bolsonaro\u00a0em que foi questionado maneiras poss\u00edveis de fraudar a urna eletr\u00f4nica.<\/p>\n\n\n\n<p>Fonte: Metro1 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante sess\u00e3o da Comiss\u00e3o Parlamentar Mista de Inqu\u00e9rito (CPMI) do 8 de janeiro desta quarta-feira (18), a deputada federal Carla Zambelli (PL-SP) citou xingamentos que recebeu em suas redes sociais, o que irritou o presidente do colegiado, o baiano Arthur Maia (Uni\u00e3o). No relat\u00f3rio da senadora Eliziane Gama (PSD-MA)\u00a0que inclui nomes,\u00a0como o do ex-presidente Jair [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[],"class_list":["post-4697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4697"}],"version-history":[{"count":0,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4697\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/4698"}],"wp:attachment":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}