{"id":4124,"date":"2023-09-27T16:08:53","date_gmt":"2023-09-27T19:08:53","guid":{"rendered":"https:\/\/diabahia.com.br\/?p=4124"},"modified":"2023-09-27T16:08:55","modified_gmt":"2023-09-27T19:08:55","slug":"novo-pac-lula-lanca-edital-de-r-655-bi-em-recursos-para-municipios","status":"publish","type":"post","link":"https:\/\/diabahia.com.br\/index.php\/2023\/09\/27\/novo-pac-lula-lanca-edital-de-r-655-bi-em-recursos-para-municipios\/","title":{"rendered":"Novo PAC: Lula lan\u00e7a edital de R$ 65,5 bi em recursos para munic\u00edpios"},"content":{"rendered":"\n<p>O presidente Luiz In\u00e1cio Lula da Silva lan\u00e7ou, nesta quarta-feira (27), o edital Sele\u00e7\u00f5es, modalidade do Novo Programa de Acelera\u00e7\u00e3o do Crescimento (PAC) voltada para atender os projetos priorit\u00e1rios apresentados por estados e munic\u00edpios em \u00e1reas essenciais como sa\u00fade, educa\u00e7\u00e3o, infraestrutura social e urbana e mobilidade. Na primeira etapa, est\u00e3o previstos R$ 65,2 bilh\u00f5es em investimentos.<\/p>\n\n\n\n<p>Em cerim\u00f4nia no Pal\u00e1cio do Planalto, Lula pediu aos gestores dos projetos que contratem trabalhadores locais para tocar as obras do Novo PAC. Um dos principais objetivos do programa \u00e9 a gera\u00e7\u00e3o de emprego e renda.<\/p>\n\n\n\n<p>\u201cVamos contratar as pessoas da cidade, vamos contratar pessoas da comunidade, porque sen\u00e3o uma empresa vai fazer uma obra numa cidade vizinha, leva trabalhadores de outra cidade, e a cidade que est\u00e1 recebendo a obra n\u00e3o consegue gerar nenhum emprego\u201d, disse.<\/p>\n\n\n\n<p>\u201cQuero pedir a compreens\u00e3o dos prefeitos, dos governadores, dos empres\u00e1rios. Na medida do poss\u00edvel, na hora de contratar os trabalhadores, vamos saber se na comunidade tem gente para fazer a obra que voc\u00eas precisam, porque a gente gera emprego na comunidade, a gente gera desenvolvimento, gera com\u00e9rcio, a gente faz o dinheiro circular na comunidade. E vou dizer mais: a gente diminui a bandidagem na comunidade se a gente gerar emprego, sal\u00e1rio e renda\u201d, acrescentou.<\/p>\n\n\n\n<p>Lula disse ainda que ontem (26) teve um \u201cmomento de muita felicidade\u201d ao ver o presidente dos Estados Unidos, Joe Biden, durante um piquete de greve de trabalhadores do setor automotivo. Na semana passada, em Nova York, os Lula e Biden lan\u00e7aram uma iniciativa global pelo trabalho decente.<\/p>\n\n\n\n<p>Para o brasileiro, \u00e9 importante perceber que existem as mesmas preocupa\u00e7\u00f5es entre l\u00edderes mundiais com rela\u00e7\u00e3o \u00e0 quest\u00e3o do mundo do trabalho. \u201cO mundo do trabalho est\u00e1 ficando precarizado. Mesmo a gente discutindo muita inova\u00e7\u00e3o, mesmo [com] essa revolu\u00e7\u00e3o digital, o que a gente percebe \u00e9 que tem muita gente trabalhando em condi\u00e7\u00f5es quase sub-humanas. E o que n\u00f3s queremos \u00e9 tentar criar condi\u00e7\u00f5es para que o trabalho dessas pessoas, inclusive que trabalham em plataforma, seja dignificado\u201d, disse.<\/p>\n\n\n\n<p>\u201cA gente n\u00e3o quer exigir que ele tenha carteira profissional assinada se ele n\u00e3o quiser. Ele tem direito de ser um empreendedor, ele tem direito de trabalhar por conta. O que a gente tem \u00e9 preocupa\u00e7\u00e3o de garantir para ele um sistema de seguridade social [em] que, quando estiver em uma situa\u00e7\u00e3o dif\u00edcil, tenha o Estado para dar a ele um suporte de sobreviv\u00eancia m\u00ednima, que \u00e9 o que todo trabalhador precisa\u201d, explicou Lula.<\/p>\n\n\n\n<p>O presidente destacou que os projetos de infraestrutura tamb\u00e9m t\u00eam potencial de estimular o esporte e a leitura, por exemplo, com a constru\u00e7\u00e3o de quadras, equipamentos esportivos e bibliotecas. Segundo Lula, o est\u00edmulo \u00e0 leitura \u00e9 uma preocupa\u00e7\u00e3o do seu governo.<\/p>\n\n\n\n<p>\u201cCada novo projeto do Minha Casa, Minha Vida tem que ter uma salinha, por menor que seja, para inicia\u00e7\u00e3o daquela crian\u00e7a numa primeira biblioteca, a biblioteca da vida dele, no bairro dele\u201d, disse. \u201c\u00c9 muito importante que a gente fa\u00e7a com que a crian\u00e7a n\u00e3o perca o h\u00e1bito da leitura. Teremos que fazer muito mais coisas que estimulem as crian\u00e7as a ler, porque sen\u00e3o as crian\u00e7as ficam o tempo inteiro no celular e terminam aprendendo menos a ler e menos a escrever\u201d, ressaltou.<\/p>\n\n\n\n<p>No discurso, Lula falou ainda sobre a participa\u00e7\u00e3o direta dos governadores e prefeitos na escolha dos investimentos do Novo PAC. Segundo ele, o governo quer \u201ccriar a ideia definitiva\u201d de que \u201co ente federativo precisa prevalecer\u201d, independente de simpatia e filia\u00e7\u00e3o pol\u00edticas entre os mandat\u00e1rios.<\/p>\n\n\n\n<p><strong>Crit\u00e9rios de sele\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>O edital do PAC Sele\u00e7\u00f5es estar\u00e1 aberto de 9 de outubro a 10 de novembro para receber as propostas dos governadores e prefeitos.<\/p>\n\n\n\n<p>A segunda etapa do Sele\u00e7\u00f5es, com mais R$ 70,8 bilh\u00f5es, dever\u00e1 ser lan\u00e7ada no in\u00edcio de 2025, para que os prefeitos que forem eleitos no ano que vem possam participar do Novo PAC. Os projetos ser\u00e3o distribu\u00eddos em 27 modalidades e executados pelos minist\u00e9rios das Cidades, da Sa\u00fade, Educa\u00e7\u00e3o, Cultura, Justi\u00e7a e Seguran\u00e7a P\u00fablica e Esporte.<\/p>\n\n\n\n<p>O PAC Sele\u00e7\u00f5es ter\u00e1 crit\u00e9rios predefinidos. Na \u00e1rea de infraestrutura urbana, a sele\u00e7\u00e3o ser\u00e1 para projetos de urbaniza\u00e7\u00e3o de favelas, regulariza\u00e7\u00e3o fundi\u00e1ria, abastecimento de \u00e1gua, esgotamento sanit\u00e1rio, res\u00edduos s\u00f3lidos, mobilidade urbana e preven\u00e7\u00e3o a desastres naturais.<\/p>\n\n\n\n<p>Na sa\u00fade, ser\u00e3o aceitas propostas para a implanta\u00e7\u00e3o de policl\u00ednicas, unidades b\u00e1sicas de sa\u00fade (UBSs), centros de parto normal e centrais do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu), entre outros. J\u00e1 na educa\u00e7\u00e3o, a sele\u00e7\u00e3o ser\u00e1 para projetos de creches, escolas e \u00f4nibus escolares; no esporte, para espa\u00e7os esportivos comunit\u00e1rios; na cultura, para projetos de patrim\u00f4nio hist\u00f3rico e centros de artes e esportes unificados (CEUs); e na seguran\u00e7a, para a constru\u00e7\u00e3o de Centros Comunit\u00e1rios pela Vida (Convive).<\/p>\n\n\n\n<p>A prioridade na sele\u00e7\u00e3o ser\u00e1 para localidades com vazios assistenciais e onde forem identificados mais car\u00eancia dentro de casa modalidade. As obras devem ser iniciadas a partir de mar\u00e7o do ano que vem, ap\u00f3s os processos de escolha dos projetos e licita\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Total de investimentos<\/strong><\/p>\n\n\n\n<p>Com previs\u00e3o total de R$ 1,7 trilh\u00e3o em investimentos p\u00fablicos e privados, o Novo PAC foi lan\u00e7ado no m\u00eas passado pelo presidente Lula. O ministro da Casa Civil, Rui Costa, afirmou que, al\u00e9m do Sele\u00e7\u00f5es, os munic\u00edpios j\u00e1 est\u00e3o contemplados com a retomada das obras paradas.<\/p>\n\n\n\n<p>\u201cTodas essas obras, que incluem creches, postos de sa\u00fade, obras urbanas, obras vi\u00e1rias, de macrodrenagem, todas elas independentes do munic\u00edpio, dos estados brasileiros, elas foram incorporadas automaticamente ao PAC e j\u00e1 est\u00e3o rodando, com aloca\u00e7\u00e3o de recurso, com atualiza\u00e7\u00e3o dos valores da obra. E agora entra essa nova fase com novas obras para cada munic\u00edpio brasileiro e cada estado, onde n\u00f3s queremos fazer um processo transparente e amplo\u201d, disse o ministro.<\/p>\n\n\n\n<p>Os principais objetivos do programa s\u00e3o gerar emprego e renda, reduzir desigualdades sociais e regionais e acelerar o crescimento econ\u00f4mico. Segundo o governo, as a\u00e7\u00f5es do programa est\u00e3o comprometidas com a transi\u00e7\u00e3o ecol\u00f3gica, a neoindustrializa\u00e7\u00e3o, o crescimento com inclus\u00e3o social e a sustentabilidade ambiental.<\/p>\n\n\n\n<p>Do total de recursos para o Novo PAC, R$ 371 bilh\u00f5es vir\u00e3o do Or\u00e7amento Geral da Uni\u00e3o. O setor privado entrar\u00e1 com R$ 612 bilh\u00f5es, as empresas estatais v\u00e3o aportar R$ 343 bilh\u00f5es, especialmente a Petrobras, e mais R$ 362 bilh\u00f5es vir\u00e3o de financiamentos. A previs\u00e3o \u00e9 que R$ 1,4 trilh\u00e3o sejam aplicados at\u00e9 2026 e o restante ap\u00f3s essa data.<\/p>\n\n\n\n<p>Fonte: Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Luiz In\u00e1cio Lula da Silva lan\u00e7ou, nesta quarta-feira (27), o edital Sele\u00e7\u00f5es, modalidade do Novo Programa de Acelera\u00e7\u00e3o do Crescimento (PAC) voltada para atender os projetos priorit\u00e1rios apresentados por estados e munic\u00edpios em \u00e1reas essenciais como sa\u00fade, educa\u00e7\u00e3o, infraestrutura social e urbana e mobilidade. Na primeira etapa, est\u00e3o previstos R$ 65,2 bilh\u00f5es em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[],"class_list":["post-4124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4124"}],"version-history":[{"count":0,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/4125"}],"wp:attachment":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}