{"id":4014,"date":"2023-09-25T11:30:19","date_gmt":"2023-09-25T14:30:19","guid":{"rendered":"https:\/\/diabahia.com.br\/?p=4014"},"modified":"2023-09-25T11:30:21","modified_gmt":"2023-09-25T14:30:21","slug":"marido-de-walewska-revela-mensagem-da-ex-jogadora-momentos-antes-da-morte","status":"publish","type":"post","link":"https:\/\/diabahia.com.br\/index.php\/2023\/09\/25\/marido-de-walewska-revela-mensagem-da-ex-jogadora-momentos-antes-da-morte\/","title":{"rendered":"Marido de Walewska revela mensagem da ex-jogadora momentos antes da morte"},"content":{"rendered":"\n<p>O corretor de im\u00f3veis Ricardo Alexandre Mendes, marido de\u00a0Walewska, revelou mensagens da esposa momentos antes da sua morte. Ela\u00a0caiu do 17\u00ba andar do pr\u00e9dio em que morava em S\u00e3o Paulo, na \u00faltima quinta-feira (21). As informa\u00e7\u00f5es s\u00e3o do portal Uol.<\/p>\n\n\n\n<p>Conforme print do WhatsApp, a ex-jogadora teria encaminhado uma mensagem para o marido \u00e0s 18h07, com a frase: &#8220;Amo voc\u00ea. Mas, acho que voc\u00ea j\u00e1 tomou a sua decis\u00e3o&#8221;. Imediatamente, Ricardo responde: &#8220;Tamb\u00e9m te amo&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/diabahia.com.br\/wp-content\/uploads\/2023\/09\/image-2.png\" alt=\"\" class=\"wp-image-4016\" srcset=\"https:\/\/diabahia.com.br\/wp-content\/uploads\/2023\/09\/image-2.png 450w, https:\/\/diabahia.com.br\/wp-content\/uploads\/2023\/09\/image-2-225x300.png 225w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/figure>\n\n\n\n<p>Segundo apontam as investiga\u00e7\u00f5es, por volta de 8 minutos ap\u00f3s a mensagem para o marido, ela teria atentado contra a pr\u00f3pria vida.<\/p>\n\n\n\n<p>Ricardo, que \u00e9 corretor de im\u00f3veis e j\u00e1 foi preparador f\u00edsico e empres\u00e1rio da esposa, explicou ao Uol que todas as \u00e1reas de conviv\u00eancia do pr\u00e9dio possuem biometria facial. Desta forma, somente as pessoas cadastradas e residentes possuem acesso aos locais de \u00e1rea comum.<\/p>\n\n\n\n<p>A investiga\u00e7\u00e3o ainda diz que Wal teria entrado sozinha na \u00e1rea da piscina, que fica no 17\u00ba andar, e l\u00e1 duas testemunhas teriam visto a ex-jogadora. Segundo relatos, aparentemente normal, sem demonstrar preocupa\u00e7\u00e3o ou tristeza.<\/p>\n\n\n\n<p>Fonte: Bnews <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O corretor de im\u00f3veis Ricardo Alexandre Mendes, marido de\u00a0Walewska, revelou mensagens da esposa momentos antes da sua morte. Ela\u00a0caiu do 17\u00ba andar do pr\u00e9dio em que morava em S\u00e3o Paulo, na \u00faltima quinta-feira (21). As informa\u00e7\u00f5es s\u00e3o do portal Uol. Conforme print do WhatsApp, a ex-jogadora teria encaminhado uma mensagem para o marido \u00e0s 18h07, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4015,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[],"class_list":["post-4014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4014"}],"version-history":[{"count":0,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4014\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/4015"}],"wp:attachment":[{"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diabahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}